{"id":3780,"date":"2016-12-20T10:09:25","date_gmt":"2016-12-20T08:09:25","guid":{"rendered":"https:\/\/outilstice.com\/?p=3780"},"modified":"2026-05-12T08:14:06","modified_gmt":"2026-05-12T06:14:06","slug":"maps-in-seconds-creez-une-carte-avec-vos-donnees-en-quelques-secondes","status":"publish","type":"post","link":"https:\/\/outilstice.com\/es\/2016\/12\/maps-in-seconds-creez-une-carte-avec-vos-donnees-en-quelques-secondes\/","title":{"rendered":"Mapas en segundos. Crea un mapa con tus datos en segundos"},"content":{"rendered":"<p><strong>Mapas en segundos<\/strong> es una herramienta online que permite <strong>Crear en segundos un mapa con datos de una hoja de c\u00e1lculo.<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-3781\" src=\"https:\/\/outilstice.com\/wp-content\/uploads\/2016\/12\/MapInSeconds.jpg\" alt=\"Mapas en segundos\" width=\"615\" height=\"471\" srcset=\"https:\/\/outilstice.com\/wp-content\/uploads\/2016\/12\/MapInSeconds.jpg 851w, https:\/\/outilstice.com\/wp-content\/uploads\/2016\/12\/MapInSeconds-300x230.jpg 300w, https:\/\/outilstice.com\/wp-content\/uploads\/2016\/12\/MapInSeconds-768x588.jpg 768w\" sizes=\"auto, (max-width: 615px) 100vw, 615px\" \/><\/p>\n<p>Nunca ha sido tan f\u00e1cil crear infograf\u00edas y mapas. Las herramientas en l\u00ednea son muy numerosas. Usted encontrar\u00e1 una peque\u00f1a muestra aqu\u00ed con <a title=\"Herramientas de geograf\u00eda\" href=\"https:\/\/outilstice.com\/tag\/geographie\/\" target=\"_blank\">algunas herramientas que tuve la oportunidad de presentar sobre las herramientas del TPCE.<\/a><\/p>\n<p><strong>Mapas en segundos es parte de esta categor\u00eda de herramientas que intenta simplificar el ejercicio de formato de datos visuales tanto como sea posible.<\/strong> Con Maps in Seconds, incluso se puede decir que es dif\u00edcil hacerlo m\u00e1s simple. La plataforma no permite el formato complejo, ni maneja datos de m\u00faltiples entradas. Si tiene una fuente de datos para comparar entre diferentes pa\u00edses, regiones, ciudades, Maps in Seconds le permitir\u00e1 crear un mapa con sus datos, como su nombre indica, en segundos.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-3782\" src=\"https:\/\/outilstice.com\/wp-content\/uploads\/2016\/12\/MapInSeconds2.jpg\" alt=\"MapasEn segundo lugar\" width=\"1198\" height=\"391\" srcset=\"https:\/\/outilstice.com\/wp-content\/uploads\/2016\/12\/MapInSeconds2.jpg 1198w, https:\/\/outilstice.com\/wp-content\/uploads\/2016\/12\/MapInSeconds2-300x98.jpg 300w, https:\/\/outilstice.com\/wp-content\/uploads\/2016\/12\/MapInSeconds2-768x251.jpg 768w, https:\/\/outilstice.com\/wp-content\/uploads\/2016\/12\/MapInSeconds2-1024x334.jpg 1024w\" sizes=\"auto, (max-width: 1198px) 100vw, 1198px\" \/><\/p>\n<p><strong>El video corto en la primera p\u00e1gina del sitio no contiene ning\u00fan comentario y le da instrucciones de uso.<\/strong> Copia de la hoja de c\u00e1lculo los datos que desea iluminar con una tarjeta y, a continuaci\u00f3n, elige la tarjeta de fondo adecuada. Todo lo que tiene que hacer es pegar sus datos en la hoja de c\u00e1lculo incorporada, el formato es inmediato. A continuaci\u00f3n, puede descargar su tarjeta a su computadora en formato PNG o PowerPoint o compartirla por correo electr\u00f3nico o en las redes sociales.<\/p>\n<p>Mapas en segundos ofrece muchos fondos de mapas. <strong>Para Francia tendr\u00e1 la opci\u00f3n de elegir entre un mapa de ciudades, cantones, departamentos y regiones.<\/strong><\/p>\n<p>Maps in Seconds es gratis y sin publicidad. No necesitar\u00e1s registrarte para usarlo.<\/p>\n<p>Enlace: <a title=\"Mapsinsegundos\" href=\"http:\/\/mapinseconds.com\/\" target=\"_blank\" rel=\"nofollow noopener\"><strong>Mapas en segundos.<\/strong><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Maps in Seconds es una herramienta en l\u00ednea que le permite crear un mapa con datos de hojas de c\u00e1lculo en segundos. Nunca ha sido tan f\u00e1cil hacer infograf\u00edas...<\/p>","protected":false},"author":1,"featured_media":3781,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[87,3],"tags":[25,80],"class_list":["post-3780","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geographie","category-utilitaires","tag-infographie","tag-utilitaires"],"modified_by":"Fidel Navamuel","_links":{"self":[{"href":"https:\/\/outilstice.com\/es\/wp-json\/wp\/v2\/posts\/3780","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/outilstice.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/outilstice.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/outilstice.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/outilstice.com\/es\/wp-json\/wp\/v2\/comments?post=3780"}],"version-history":[{"count":1,"href":"https:\/\/outilstice.com\/es\/wp-json\/wp\/v2\/posts\/3780\/revisions"}],"predecessor-version":[{"id":16184,"href":"https:\/\/outilstice.com\/es\/wp-json\/wp\/v2\/posts\/3780\/revisions\/16184"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/outilstice.com\/es\/wp-json\/wp\/v2\/media\/3781"}],"wp:attachment":[{"href":"https:\/\/outilstice.com\/es\/wp-json\/wp\/v2\/media?parent=3780"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/outilstice.com\/es\/wp-json\/wp\/v2\/categories?post=3780"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/outilstice.com\/es\/wp-json\/wp\/v2\/tags?post=3780"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}